{"id":19642,"date":"2023-06-07T17:04:55","date_gmt":"2023-06-07T15:04:55","guid":{"rendered":"https:\/\/swiss-soroptimist.ch\/?p=19642"},"modified":"2025-02-18T00:13:25","modified_gmt":"2025-02-17T23:13:25","slug":"club-lavaux-loto","status":"publish","type":"post","link":"https:\/\/swiss-soroptimist.ch\/fr\/club-lavaux-loto\/","title":{"rendered":"Club Lavaux | Loto"},"content":{"rendered":"<h2>Organisation d&rsquo;un loto pour financer nos boursi\u00e8res<\/h2>\n<p>Nous avons organis\u00e9 le 9 mai notre traditionnel loto dans la grande salle communale de Pully. Il a remport\u00e9 un beau succ\u00e8s et rassembl\u00e9 un grand nombre de personnes dans une ambiance tr\u00e8s conviviale.<br \/>\nNous avons \u00e9t\u00e9 heureuses de renouer avec cette manifestation apr\u00e8s l&rsquo;\u00e9dition manqu\u00e9e de 2021.<br \/>\nLe b\u00e9n\u00e9fice de cette soir\u00e9e sera attribu\u00e9 \u00e0 nos actions sociales et en priorit\u00e9, \u00e0 l\u2019octroi de bourses d\u2019apprentissage \u00e0 des femmes de la r\u00e9gion en difficult\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organisation d&rsquo;un loto pour financer nos boursi\u00e8res Nous avons organis\u00e9 le 9 mai notre traditionnel loto dans la grande salle communale de Pully. Il a remport\u00e9 un beau succ\u00e8s et rassembl\u00e9 un grand nombre de personnes dans une ambiance tr\u00e8s conviviale. Nous avons \u00e9t\u00e9 heureuses de renouer avec cette manifestation apr\u00e8s l&rsquo;\u00e9dition manqu\u00e9e de 2021. <a href=\"https:\/\/swiss-soroptimist.ch\/fr\/club-lavaux-loto\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":200,"featured_media":19609,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[132,133],"tags":[],"class_list":["post-19642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-berichte-clubs-2023-fr","category-rapports-des-clubs-2023"],"_links":{"self":[{"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/posts\/19642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/users\/200"}],"replies":[{"embeddable":true,"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/comments?post=19642"}],"version-history":[{"count":1,"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/posts\/19642\/revisions"}],"predecessor-version":[{"id":19643,"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/posts\/19642\/revisions\/19643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/media\/19609"}],"wp:attachment":[{"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/media?parent=19642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/categories?post=19642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swiss-soroptimist.ch\/fr\/wp-json\/wp\/v2\/tags?post=19642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}